{"id":1,"date":"2024-12-06T03:04:36","date_gmt":"2024-12-06T03:04:36","guid":{"rendered":"https:\/\/blog.sapsc.mx\/?p=1"},"modified":"2024-12-06T16:17:13","modified_gmt":"2024-12-06T16:17:13","slug":"hello-world","status":"publish","type":"post","link":"https:\/\/blog.sapsc.mx\/index.php\/2024\/12\/06\/hello-world\/","title":{"rendered":"7ma Resoluci\u00f3n de Modificaciones a las Reglas de Comercio Exterior 2020"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Al margen un sello con el Escudo Nacional, que dice: Estados Unidos Mexicanos.- HACIENDA.- Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico.- Servicio de Administraci\u00f3n Tributaria.<\/p>\n\n\n\n\n\n<p><strong>S\u00e9ptima Resoluci\u00f3n de Modificaciones a las Reglas Generales de Comercio Exterior para 2020<\/strong><\/p>\n\n\n\n<p>El Servicio de Administraci\u00f3n Tributaria, con fundamento en los art\u00edculos 16 y 31 de la Ley Org\u00e1nica de la Administraci\u00f3n P\u00fablica Federal; 1\u00ba y 144 de la Ley Aduanera; 33, fracci\u00f3n I, inciso g), del C\u00f3digo Fiscal de la Federaci\u00f3n; 14, fracci\u00f3n III, de la Ley del Servicio de Administraci\u00f3n Tributaria, y 8 del Reglamento Interior del Servicio de Administraci\u00f3n Tributaria, resuelve:<\/p>\n\n\n\n<p><strong>Primero.<\/strong> Se reforman las reglas 1.9.19.; 2.4.1., primer p\u00e1rrafo; 2.4.11.; 3.1.17., segundo p\u00e1rrafo; 3.1.19., segundo p\u00e1rrafo; 3.1.21., p\u00e1rrafo primero, fracci\u00f3n III, inciso a); 3.1.24., p\u00e1rrafos primero y actual quinto; 3.1.31., primer p\u00e1rrafo; 3.1.32., p\u00e1rrafos primero, en su encabezado, y segundo; 3.1.33., p\u00e1rrafo primero, fracci\u00f3n I, p\u00e1rrafos segundo y tercero, y se adicionan las reglas 3.1.15., con una fracci\u00f3n V; 3.1.24., con un segundo p\u00e1rrafo, pasando los actuales segundo, tercero, cuarto, quinto y sexto p\u00e1rrafos a ser tercero, cuarto, quinto, sexto y s\u00e9ptimo p\u00e1rrafos respectivamente; 3.1.32., con una fracci\u00f3n VIII y 3.1.33., fracci\u00f3n I, con un inciso g) y un cuarto p\u00e1rrafo, pasando el actual cuarto p\u00e1rrafo a ser quinto p\u00e1rrafo, de las Reglas Generales de Comercio Exterior para 2020, para quedar de la siguiente manera:<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>N\u00famero de acuse de valor consolidado<\/strong><\/h6>\n\n\n\n<p>1.9.19. Para los efectos de los art\u00edculos 37 y 37-A de la Ley, cuando se opte por presentar un pedimento consolidado, los agentes aduanales, las agencias aduanales o personas autorizadas para el despacho aduanero de las mercanc\u00edas estar\u00e1n a lo siguiente:<\/p>\n\n\n\n<p>I. Transmitir\u00e1n electr\u00f3nicamente a la autoridad aduanera a trav\u00e9s de la Ventanilla Digital los siguientes datos:<\/p>\n\n\n\n<p>a) Los se\u00f1alados en la regla 3.1.8., contenidos en el documento a que se refiere el art\u00edculo 37-A, fracciones I y II de la Ley.<br>b) El RFC o n\u00famero de registro de identificaci\u00f3n fiscal del destinatario, del comprador de las mercanc\u00edas cuando sea distinto del destinatario, y del vendedor o proveedor de las mismas. Para efectos del consignatario, el RFC o n\u00famero de registro de identificaci\u00f3n fiscal deber\u00e1 ser declarado en el campo de observaciones del pedimento, de conformidad con el Anexo 22.<br>c) Los e-documents correspondientes a los documentos digitales que comprueben el cumplimiento de las regulaciones y restricciones no arancelarias, en t\u00e9rminos de la regla 3.1.31.<\/p>\n\n\n\n<p>II. La transmisi\u00f3n a que se refiere la fracci\u00f3n anterior deber\u00e1 realizarse previo al despacho aduanero de las mercanc\u00edas y se sujetar\u00e1 a lo siguiente:<\/p>\n\n\n\n<p>a) Deber\u00e1 efectuarse con la e.firma del agente aduanal, agencia aduanal o apoderado aduanal, o del importador o exportador, el primero de \u00e9stos lo podr\u00e1 realizar por conducto de su mandatario autorizado.<br>b) Se deber\u00e1 realizar en idioma espa\u00f1ol, o bien, cuando los documentos se encuentren en ingl\u00e9s o franc\u00e9s, podr\u00e1 realizarse en estos idiomas.<br>c) Cuando el documento equivalente que exprese el valor de las mercanc\u00edas contenga una declaraci\u00f3n bajo protesta de decir verdad o dicha declaraci\u00f3n se se\u00f1ale en un escrito libre, de conformidad con las disposiciones jur\u00eddicas aplicables, se deber\u00e1 asentar la declaraci\u00f3n en la transmisi\u00f3n, cumpliendo con las dem\u00e1s formalidades aplicables a cada caso.<\/p>\n\n\n\n<p>Una vez transmitida la informaci\u00f3n, se recibir\u00e1 un acuse de referencia emitido por la Ventanilla Digital denominado \u00abn\u00famero del acuse de valor\u00bb, el cual se manifestar\u00e1 en el aviso consolidado, en el pedimento consolidado, en la transmisi\u00f3n del documento electr\u00f3nico a que se refieren las reglas 2.4.11., fracci\u00f3n I y 3.1.33., fracci\u00f3n I, o en el c\u00f3digo de barras a que se refiere el Ap\u00e9ndice 17 del Anexo 22 de la impresi\u00f3n del \u00abFormato de Aviso Consolidado\u00bb del Anexo 1.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Autorizaci\u00f3n para el despacho en lugar distinto al autorizado<\/strong><\/h6>\n\n\n\n<p>2.4.1. Para los efectos de los art\u00edculos 10, segundo p\u00e1rrafo, de la Ley y 11 del Reglamento, las personas morales interesadas en obtener la autorizaci\u00f3n para la entrada o salida de mercanc\u00edas del territorio nacional por lugar distinto al autorizado o, en su caso, la pr\u00f3rroga de la misma, podr\u00e1n solicitar autorizaci\u00f3n, de conformidad con la ficha de tr\u00e1mite 49\/LA del Anexo 1-A. \u00danicamente se podr\u00e1 otorgar la citada autorizaci\u00f3n o, en su caso, pr\u00f3rroga, a las empresas productivas del Estado, sus organismos subsidiarios y empresas productivas subsidiarias, trat\u00e1ndose de las siguientes mercanc\u00edas:<\/p>\n\n\n\n<p>I. Los hidrocarburos, productos petrol\u00edferos, incluso mezclados con otros componentes que no provengan del petr\u00f3leo o gas natural, petroqu\u00edmicos y sus especialidades, as\u00ed como biocombustibles, incluyendo los listados en los Sectores 12 \u00abAlcohol Et\u00edlico\u00bb y 13 \u00abHidrocarburos y Combustibles\u00bb, del Apartado A, del Anexo 10 y en el Anexo 14.<br>II. Los precursores qu\u00edmicos de:<br>a) Fentanilo que se clasifiquen en las fracciones arancelarias: 2903.99.99, 2921.41.01, 2933.33.03, 2933.39.24, 2933.39.99.<br>b) Metanfetamina que se clasifiquen en las fracciones arancelarias: 2811.19.99, 2837.19.99, 2903.12.01, 2904.20.99, 2912.11.01, etc.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Transitorios<\/strong><\/h6>\n\n\n\n<p><strong>Primero.<\/strong> La presente Resoluci\u00f3n entrar\u00e1 en vigor a los 30 d\u00edas siguientes al de su publicaci\u00f3n en el DOF, con excepci\u00f3n de lo siguiente:<\/p>\n\n\n\n<p>I. Lo dispuesto en la regla 2.4.11., fracci\u00f3n I, inciso f); 3.1.31, primer p\u00e1rrafo; 3.1.32., fracci\u00f3n VIII, y 3.1.33., fracci\u00f3n I, inciso g), entrar\u00e1 en vigor el 30 de septiembre de 2021.<br>II. La reforma a la regla 2.4.1., as\u00ed como lo dispuesto en el resolutivo tercero, entrar\u00e1n en vigor el d\u00eda siguiente al de su publicaci\u00f3n en el DOF.<\/p>\n\n\n\n<p>\u200d<\/p>\n\n\n\n<p>Atentamente,<br>Ciudad de M\u00e9xico, a 08 de junio de 2021.- La Jefa del Servicio de Administraci\u00f3n Tributaria, Raquel Buenrostro S\u00e1nchez.- R\u00fabrica.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al margen un sello con el Escudo Nacional, que dice: Estados Unidos Mexicanos.- HACIENDA.- Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico.- Servicio de Administraci\u00f3n Tributaria. S\u00e9ptima Resoluci\u00f3n de Modificaciones a las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[4,10,13,14,11],"class_list":["post-1","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-comercio","tag-comercio-exterior","tag-ley","tag-reglamento","tag-reglas","bwp-blog-post","bwp-masonry-item","bwp-col-3","bwp-post-has-title"],"_links":{"self":[{"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":2,"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":19,"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions\/19"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/media\/18"}],"wp:attachment":[{"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.sapsc.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}